{"id":1371,"date":"2024-03-13T13:54:39","date_gmt":"2024-03-13T12:54:39","guid":{"rendered":"https:\/\/sopsy-si.ch\/?p=1371"},"modified":"2024-03-13T14:28:04","modified_gmt":"2024-03-13T13:28:04","slug":"corso-di-perfezionamento-in-medicina-psicosomatica-e-psicosociale-2025-2026","status":"publish","type":"post","link":"https:\/\/sopsy-si.ch\/index.php\/2024\/03\/13\/corso-di-perfezionamento-in-medicina-psicosomatica-e-psicosociale-2025-2026\/","title":{"rendered":"Corso di perfezionamento  in medicina  psicosomatica e psicosociale 2025-2026"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1372\" src=\"https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/03\/convegno.jpg\" alt=\"\" width=\"288\" height=\"175\" srcset=\"https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/03\/convegno-200x122.jpg 200w, https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/03\/convegno.jpg 288w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/><\/p>\n<p>Organizzato da:<br \/>\n<strong>Istituto Ticinese di Formazione in\u00a0<\/strong><strong> Medicina Psicosomatica e Psicosociale <\/strong><strong>IS-TI-PSISO<\/strong><\/p>\n<p>In collaborazione con:<\/p>\n<p>TI-PSISO<br \/>\nGruppo Regionale dell\u2019Accademia Svizzera di<br \/>\nMedicina Psicosomatica e Psicosociale\u00a0EOC<br \/>\nEnte Ospedaliero Cantonale\u00a0\u00a0USI<br \/>\nUniversit\u00e0 della Svizzera Italiana OSC<br \/>\nOrganizzazione sociopsichiatrica Cantonale<\/p>\n<p><strong>Il corso \u00e8 patrocinato da OMCT<br \/>\n<\/strong><strong>Ordine dei medici del Canton Ticino<\/strong><\/p>\n<p>L\u2019Istituto Ticinese di formazione in Medicina Psico-somatica e Psicosociale IS-TI-PSISO ha organizzato dal 2001 6 corsi biennali, completi e impegnativi, che hanno formato 80 medici e 6 professionisti para-medici della Svizzera italiana in medicina psicosomatica e psicosociale.<br \/>\nNel periodo 2025-2026 offrir\u00e0 il settimo corso biennale che potr\u00e0 portare all\u2019ottenimento del titolo di formazione interdisciplinare approfondita in medicina psicosomatica e psicosociale.<br \/>\nL\u2019IS-TI-PSISO \u00e8 un istituto di formazione riconosciuto dall\u2019Accademia Svizzera di Medicina Psicosomatica e Psicosociale (ASMPP).<br \/>\n<strong>L\u2019ASMPP organizza e sorveglia la formazione in medicina psicosomatica per medici su incarico dell\u2019 FMH.<\/strong><\/p>\n<p><strong><u>Concetto del corso<\/u><\/strong><\/p>\n<p>La medicina psicosomatica e psicosociale ha come obiettivo l\u2019integrazione di aspetti biologici e psico-sociali nella comprensione della malattia e della persona malata. La premessa di fondo su cui si basa lo sviluppo di una medicina psicosomatica e psicosociale \u00e8 che mente e corpo non sono due entit\u00e0 separate operanti indipendentemente, bens\u00ec due aspetti distinti, ma integrati di una persona.<br \/>\nQuesta integrazione \u00e8 particolarmente indicata nelle situazioni in cui gli aspetti psicosociali sono ricono-scibili nell\u2019insorgenza e nel decorso della malattia, oppure quando malattie somatiche hanno un influsso sulla situazione psicosociale del malato.<br \/>\nLa comunicazione medico \u2013 paziente assume quindi un ruolo determinante per permettere di conoscere e comprendere i vissuti, le aspettative dell\u2019altro e soprattutto gli schemi interpretativi che danno un significato ai segni scambiati nella relazione e ai sintomi del corpo.<\/p>\n<p><strong><u>Condizioni di ammissione<\/u><\/strong><\/p>\n<p>Sono richiesti almeno due anni di attivit\u00e0 clinica in ospedale o in studio medico. Per psicologi e professioni paramediche: almeno due anni di attivit\u00e0 professionale. Si richiede la disponibilit\u00e0 alla video-registrazione di colloqui con pazienti e la reperibilit\u00e0 tramite e-mail.<br \/>\nDue terzi dei partecipanti dovranno essere medici.<\/p>\n<p><strong><u>Struttura e durata del corso<\/u><\/strong><\/p>\n<p>Il corso, che durer\u00e0 da gennaio 2025 a dicembre 2026, \u00e8 costituito da:<\/p>\n<ul>\n<li>Giornate di formazione con teoria, esercizi di gruppo, giochi di ruolo (10 giornate all\u2019anno)<\/li>\n<li>Gruppi di supervisione (10 supervisioni all\u2019anno)<\/li>\n<li>Protocolli di colloqui con pazienti<\/li>\n<li>Videoregistrazioni di colloqui con pazienti<\/li>\n<li>Valutazione della qualit\u00e0 del corso stesso<\/li>\n<\/ul>\n<p><strong><u>Informazioni<\/u><\/strong><\/p>\n<p>Dr.ssa med. Maria Grazia Canepa FMH medicina interna, Presidente IS-TI-PSISO<\/p>\n<p>mgcanepa@bluewin.ch<\/p>\n<p><strong><u>Obiettivi<\/u><\/strong><\/p>\n<p>I partecipanti conseguiranno competenze specifiche nel riconoscere e trattare disturbi e malattie psicoso-matiche e psicosociali che richiedono conoscenze e capacit\u00e0 che vanno al di l\u00e0 delle abituali conoscenze del medico di base.<\/p>\n<p>In particolare il partecipante al termine del corso:<\/p>\n<ul>\n<li>conoscer\u00e0 differenti teorie di medicina psicoso-matica e psicosociale<\/li>\n<li>sapr\u00e0 differenziare vari tipi di approccio tera-peutico<\/li>\n<li>sapr\u00e0 eseguire una terapia stabilizzante, regolare e a lungo termine<\/li>\n<li>sapr\u00e0 coinvolgere il paziente come co-esperto per la sua malattia e la sua salute<\/li>\n<li>sapr\u00e0 riconoscere e valutare le proprie emozioni nell\u2019 interazione col paziente<\/li>\n<li>sapr\u00e0 rispettare i propri limiti e trovare le modalit\u00e0 adeguate nella collaborazione con vari specialisti<\/li>\n<li>sapr\u00e0 utilizzare le risorse e le competenze della rete psicosociale ticinese<\/li>\n<li>sapr\u00e0 riconoscere disturbi somatoformi<\/li>\n<\/ul>\n<p><strong><u>Corso e attestato<\/u><\/strong><\/p>\n<p>Il corso \u00e8 organizzato in modo da essere compatibile con la formazione interdisciplinare approfondita in Medicina Psicosomatica e Psicosociale, come proposto dall\u2019 Accademia Svizzera di Medicina Psicosomatica e Psicosociale (ASMPP). Tutti, anche chi non \u00e8 medico, riceveranno un attestato di formazione.<\/p>\n<p>I contenuti del curriculum formativo sono composti da:<\/p>\n<ul>\n<li>teoria e conoscenze<\/li>\n<li>acquisizione ed esercizio di competenze<\/li>\n<li>supervisione ed esperienza personale.<\/li>\n<\/ul>\n<p>Il partecipante avr\u00e0 totalizzato, dopo il corso bienna-le, 320 ore sulle 360 ore richieste dall\u2019 ASMPP per l\u2019ottenimento dell\u2019Attestato di perfezionamento.<\/p>\n<p>Le ore rimanenti potranno essere completate fre-quentando altre formazioni riconosciute dall\u2019 ASMPP, in particolare gli aggiornamenti di TI-PSISO, il Con-gresso della stessa ASMPP, come pure i gruppi di supervisione che potranno continuare anche dopo la fine del corso.<\/p>\n<p><strong><u>Programma del 1. anno \u00a0<\/u><\/strong><\/p>\n<p><strong>Elementi di base dell\u2019approccio psicosomatico e psicosociale<\/strong><\/p>\n<p>Il modello biopsicosociale nella medicina; i principi di base della comunicazione centrata sul paziente; presentazione della tecnica di apprendimento tramite analisi di \u201cincidenti critici\u201d; spiegazione di istruzioni per i giochi di ruolo; presentazione dell\u2019utilizzo della videoregistrazione come modalit\u00e0 di formazione.<\/p>\n<p><strong>Il colloquio medico \u2013 paziente<\/strong><\/p>\n<p>Presentazione di colloqui con pazienti; visione di videoregistrazioni; discussione e valutazione di col-loqui dal vivo; aspetti teorici delle tecniche di comuni-cazione centrata sul paziente; il confronto con le emozioni; riconoscere i propri limiti; il ruolo dell\u2019 esame fisico del paziente e il suo contenuto comuni-cativo; riflessione sul proprio atteggiamento nel collo-quio con i pazienti.<u><\/u><\/p>\n<p><strong>Il contributo psicodinamico alla comprensione della malattia<\/strong><\/p>\n<p>Il ruolo della psicoanalisi nello sviluppo della psico-somatica; concetti di base della psicoanalisi; mecca-nismi di difesa e coping; possibilit\u00e0 di utilizzo dell\u2019 approccio psicodinamico nella pratica clinica.<\/p>\n<p><strong>Il contributo delle scienze cognitive- comportamentali<\/strong><\/p>\n<p>Elementi di psicofisiologia, psicoimmunologia; il mo-dello dello stress; l\u2019approccio cognitivo; concetti di base degli interventi cognitivi-comportamentali.<\/p>\n<p><strong>Il contributo delle scienze sistemiche alla comprensione della malattia<\/strong><\/p>\n<p>Il sistema di cure e il sistema familiare; la formula-zione di ipotesi e la circolarit\u00e0; teoria della saluto-genesi; concetti di base dell\u2019intervento con coppie e famiglie.<\/p>\n<p><strong>Il disturbo somatoforme<\/strong><\/p>\n<p>Gestire la relazione con pazienti con disturbi somato-formi; il sintomo come \u2018chiave d\u2019entrata\u2019; creare un linguaggio comune; cercare la collaborazione del pa-ziente; definire gli obiettivi.<\/p>\n<p><strong><u>Altri temi trattati<\/u><\/strong><\/p>\n<ul>\n<li>Malattia cronica. Sindrome del dolore cronico<\/li>\n<li>Disturbi di personalit\u00e0, suicidalit\u00e0<\/li>\n<li>Perizie in medicina psicosomatica<\/li>\n<li>Psico-oncologia, accompagnamento alla morte<\/li>\n<li>Disturbi d\u2019ansia, Burn-Out<\/li>\n<li>Colloquio motivazionale<\/li>\n<li>La comunicazione secondo Milton Erickson<\/li>\n<li>Disturbi del comportamento alimentare<\/li>\n<li>Disturbi da dipendenza da alcool e da altre sostanze psicoattive<\/li>\n<li>Approccio psicocorporeo: il livello simbolico<\/li>\n<\/ul>\n<p><strong><u>Direzione del corso e team didattico<\/u><\/strong><\/p>\n<p><strong>Direzione<\/strong>: Dr.ssa med. Maria Grazia Canepa medicina interna generale FMH, med. psicosomatica e psicosociale ASMPP,terapia del dolore SPS, ipnosi medica SMSH<\/p>\n<p><strong>Team didattico<\/strong>:<\/p>\n<ul>\n<li>ssa med. Cornelia Klauser, med. generale FMH, med. psicosomatica e psicosociale ASMPP, Ipnosi medica SMSH<\/li>\n<li>a Gabriella Bianchi, psicologa e psicoterapeuta FSP<\/li>\n<li>med. Martin Zogg, med. generale FMH, med. psicosomatica e psicosociale ASMPP<\/li>\n<li>med. Marzio Sabbioni, med. interna generale FMH, psichiatria FMH, med. psicosomatica e psicosociale ASMPP<\/li>\n<li>ssa med. Maria Grazia Canepa, medicina interna generale FMH, med. psicosomatica e psicosociale ASMPP, terapia del dolore SPS, ipnosi medica SMSH<\/li>\n<\/ul>\n<p><strong><u>Luogo<\/u><\/strong><\/p>\n<p>Giornate del corso suddivise tra: OSC Mendrisio\/ EOC Bellinzona<\/p>\n<p>Supervisione: luogo da concordare (supervisori: Dr. med M. Zogg \/ G. Bianchi )<\/p>\n<p><strong><u>Costi<\/u><\/strong><\/p>\n<p>Il costo del corso a Fr. 5000.- all\u2019anno (compresa la supervisione), per un totale di Fr. 10&#8217;000.- ( pagabili anche ratealmente ; costo di una lezione: Fr. 10&#8217;000.- diviso 320 ore = Fr.31.25.-\u00a0 all\u2019ora!).<\/p>\n<p><strong>E\u2019 possibile<\/strong> <strong>partecipare a singole giornate <\/strong>al prezzo di\u00a0 Fr. 300.- ( Fr. 150 per membri Ti-PSISO)<\/p>\n<p>(In casi particolari ci si pu\u00f2 sempre rivolgere al di-rettore del corso).<\/p>\n<p><strong><u>Iscrizione<\/u><\/strong><\/p>\n<p>L\u2019iscrizione avviene tramite l\u2019invio del tagliando allegato a: <strong><a href=\"mailto:mgcanepa@bluewin.ch\">mgcanepa@bluewin.ch<\/a><\/strong> \u00a0oppure <strong><u>mgcanepa@hin,ch<\/u><\/strong> ed \u00e8 <u>vincolante<\/u><\/p>\n<p><u>per 1 anno\u00a0 !<\/u><\/p>\n<p><em>Chi non pu\u00f2 o non vuole seguire il corso completo, ma \u00e8 comunque interessato alla medicina psicosomatica, pu\u00f2<br \/>\nrivolgersi all\u2019indirizzo sopra per avere informazioni sugli aggiornamenti di TI-PSISO<br \/>\n<\/em><\/p>\n<p>[\/fusion_text][\/fusion_builder_column][\/fusion_builder_row][\/fusion_builder_container]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizzato da: Istituto Ticinese di Formazione in\u00a0 Medicina Psicosomatica e<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1371","post","type-post","status-publish","format-standard","hentry","category-appuntamenti"],"_links":{"self":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1371"}],"version-history":[{"count":7,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1371\/revisions"}],"predecessor-version":[{"id":1381,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1371\/revisions\/1381"}],"wp:attachment":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}