{"id":1422,"date":"2024-06-11T13:00:50","date_gmt":"2024-06-11T12:00:50","guid":{"rendered":"https:\/\/sopsy-si.ch\/?p=1422"},"modified":"2024-06-11T13:00:50","modified_gmt":"2024-06-11T12:00:50","slug":"vask-ticino-in-collaborazione-con-osc","status":"publish","type":"post","link":"https:\/\/sopsy-si.ch\/index.php\/2024\/06\/11\/vask-ticino-in-collaborazione-con-osc\/","title":{"rendered":"Vask Ticino in collaborazione con OSC"},"content":{"rendered":"<h3>Home treatment nel luganese<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-1423\" src=\"https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/06\/Presentazione-home-treatment-18-giugno-2024.jpg\" alt=\"\" width=\"400\" height=\"338\" srcset=\"https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/06\/Presentazione-home-treatment-18-giugno-2024-200x169.jpg 200w, https:\/\/sopsy-si.ch\/wp-content\/uploads\/2024\/06\/Presentazione-home-treatment-18-giugno-2024.jpg 400w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Care e cari familiari, care e cari amici,<br \/>\ncon \u201cHome Treatment\u201d s\u2019intende la possibilit\u00e0 di curare a domicilio una persona con un disagio psichico acuto, evitando cos\u00ec un ricovero in clinica psichiatrica.<br \/>\nTale possibilit\u00e0 \u00e8 stata fortemente caldeggiata da Vask ticino e ha dato luogo ad un primo progetto pilota nel bellinzonese. Il progetto pilota ha portato risultati interessanti sia sul piano della cura alla persona, sia sulla sua soddisfazione e su quella dei suoi familiari. Esso verr\u00e0 quindi esteso progressivamente al territorio cantonale iniziando dal luganese.<br \/>\nPer la presentazione del progetto v\u2019invitiamo alla serata che si terr\u00e0<\/p>\n<p style=\"text-align: center;\">\nMarted\u00ec 18 giugno 2024 presso il<br \/>\nCanvetto luganese via Siemen 14b, Lugano, sala Feste I piano<br \/>\nA partire dalle 18.00<\/p>\n<p><strong>Interverranno:<\/strong><br \/>\nDr.ssa Med Sara Ravasi, medico sostituto capoclinica<br \/>\nSignor Severino Cordasco, infermiere coordinatore<br \/>\nSignora Marzia Pinci, infermiera insegnante assistente<br \/>\n\u00c8 possibile posteggiare nelle vicinanze.<\/p>\n<p>Nell\u2019attesa d\u2019incontrarvi vi saluto molto cordialmente<\/p>\n<p>Monica Lupi<br \/>\nPresidente di Vask Ticino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home treatment nel luganese Care e cari familiari, care e<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1422","post","type-post","status-publish","format-standard","hentry","category-attualita"],"_links":{"self":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1422"}],"version-history":[{"count":1,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1422\/revisions"}],"predecessor-version":[{"id":1424,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/posts\/1422\/revisions\/1424"}],"wp:attachment":[{"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sopsy-si.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}